
{"id":3531,"date":"2017-07-11T15:05:34","date_gmt":"2017-07-11T20:05:34","guid":{"rendered":"https:\/\/webc2k.control2000.com.mx\/blog\/?p=3531"},"modified":"2017-07-11T15:05:34","modified_gmt":"2017-07-11T20:05:34","slug":"datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif","status":"publish","type":"post","link":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/","title":{"rendered":"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF"},"content":{"rendered":"<p>De entrada el CFDI global deber\u00e1 expedirse a m\u00e1s tardar a las 72 horas siguientes al cierre de las operaciones que lo integran, ya sea que elijan hacerlo diario, semanal, mensual o bimestral para el caso RIF donde consten los importes correspondientes a cada una de las operaciones realizadas con el p\u00fablico en general del periodo al que corresponda y, en su caso, el n\u00famero de folio o de operaci\u00f3n de los comprobantes de operaciones con el p\u00fablico en general que se hubieran emitido, utilizando para ello la clave gen\u00e9rica en el RFC a que se refiere la regla 2.7.1.26 que es la XAXX010101000. Los contribuyentes que tributen en el RIF podr\u00e1n elaborar el CFDI de referencia de forma bimestral a trav\u00e9s de Mis cuentas, incluyendo \u00fanicamente el monto total de las operaciones del bimestre y el periodo correspondiente.<br \/>\nPero como la autoridad vive en un universo paralelo ellos consideran que se deben incluir:<br \/>\n1) Los importes correspondientes a cada una de las operaciones realizadas con el p\u00fablico en general del periodo,<br \/>\n2) El n\u00famero de folio o de operaci\u00f3n de cada uno de los comprobantes de operaciones con el publico en general que se emitieron en el periodo.<br \/>\nPodr\u00eda hacerse pero tendr\u00edamos que abrir un concepto para cada n\u00famero de ticket o nota por relacionar, y la realidad es que la regla indica que se mencionen esos folios por lo que podr\u00edamos anotar en DESCRIPCI\u00d3N: VENTAS DEL D\u00cdA SEG\u00daN TICKETS EMITIDOS DEL FOLIO XXX AL FOLIO YYY. Y en lo que respecta a los contribuyentes de RIF tienen la facilidad de incluir \u00fanicamente el monto total de las operaciones del bimestre y el periodo correspondiente, por lo que podr\u00edan indicar la descripci\u00f3n de VENTAS DEL BIMESTRE DE OCTUBRE A NOVIEMBRE DE 2017 (aunque tambi\u00e9n pueden emitir la factura por d\u00eda, semana o mes).<br \/>\nLa otra opci\u00f3n es volver a llenar otra vez el detalle de cada una de las operaciones que se hicieron con el p\u00fablico en general por d\u00eda o por mes, pero en ese caso cu\u00e1l es el objetivo de un comprobante global, mejor se hubiera hecho una factura por cada operaci\u00f3n con el RFC gen\u00e9rico y listo.<br \/>\nTambi\u00e9n es importante que consideren los siguientes datos:<br \/>\nCANTIDAD: 1<br \/>\nCLAVE PROD. O SERV: 01010101<br \/>\nCLAVE UNIDAD DE MEDIDA: ACT<br \/>\nFORMA DE PAGO: La clave de la forma m\u00e1s representativa (solo es posible poner una)<br \/>\nMETODO DE PAGO: PUE (Pago en una sola exhibici\u00f3n)<br \/>\nUSO DEL CFDI: P01 Por definir.<\/p>\n<p>Como se est\u00e1 indicando que el comprobante ya se pag\u00f3, no ser\u00e1 necesario elaborar un complemento de recepci\u00f3n de pagos.<\/p>\n<p>Se consigna el importe total de las operaciones y s\u00f3lo en caso de no pertenecer al R\u00e9gimen de Incorporaci\u00f3n, desglosar el IVA y el IEPS; la raz\u00f3n, es porque debido al est\u00edmulo con el que goza el RIF desde hace varios a\u00f1os de no pagar el IVA ni el IEPS en las operaciones con el p\u00fablico en general, est\u00e1 condicionada a no desglosar los impuestos en los comprobantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De entrada el CFDI global deber\u00e1 expedirse a m\u00e1s tardar a las 72 horas siguientes al cierre de las operaciones que lo integran, ya sea que elijan hacerlo diario, semanal, mensual o bimestral para el caso RIF donde consten los importes correspondientes a cada una de las operaciones realizadas con el p\u00fablico en general del periodo al que corresponda y, [&#8230;]<a class=\"read-more read-more-c2k\" href=\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[171],"tags":[4,875,674],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000\" \/>\n<meta property=\"og:description\" content=\"De entrada el CFDI global deber\u00e1 expedirse a m\u00e1s tardar a las 72 horas siguientes al cierre de las operaciones que lo integran, ya sea que elijan hacerlo diario, semanal, mensual o bimestral para el caso RIF donde consten los importes correspondientes a cada una de las operaciones realizadas con el p\u00fablico en general del periodo al que corresponda y, [...]Continuar leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog 2000\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-11T20:05:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pen\u00e9lope Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/\",\"name\":\"Blog 2000\",\"description\":\"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#webpage\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/\",\"name\":\"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000\",\"isPartOf\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\"},\"datePublished\":\"2017-07-11T20:05:34+00:00\",\"dateModified\":\"2017-07-11T20:05:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.control2000.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\",\"name\":\"Pen\u00e9lope Castro\",\"sameAs\":[\"http:\/\/www.control2000.com.mx\"],\"url\":\"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/","og_locale":"es_ES","og_type":"article","og_title":"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000","og_description":"De entrada el CFDI global deber\u00e1 expedirse a m\u00e1s tardar a las 72 horas siguientes al cierre de las operaciones que lo integran, ya sea que elijan hacerlo diario, semanal, mensual o bimestral para el caso RIF donde consten los importes correspondientes a cada una de las operaciones realizadas con el p\u00fablico en general del periodo al que corresponda y, [...]Continuar leyendo","og_url":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/","og_site_name":"Blog 2000","article_published_time":"2017-07-11T20:05:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pen\u00e9lope Castro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.control2000.com.mx\/blog\/#website","url":"https:\/\/www.control2000.com.mx\/blog\/","name":"Blog 2000","description":"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#webpage","url":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/","name":"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF - Blog 2000","isPartOf":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#website"},"datePublished":"2017-07-11T20:05:34+00:00","dateModified":"2017-07-11T20:05:34+00:00","author":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791"},"breadcrumb":{"@id":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.control2000.com.mx\/blog\/datos-importantes-para-la-factura-global-regla-2-7-1-24-y-art-23-lif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.control2000.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Datos importantes para la factura global regla 2.7.1.24 y Art. 23 LIF"}]},{"@type":"Person","@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791","name":"Pen\u00e9lope Castro","sameAs":["http:\/\/www.control2000.com.mx"],"url":"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/"}]}},"fimg_url":false,"_links":{"self":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3531"}],"collection":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=3531"}],"version-history":[{"count":1,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3531\/revisions"}],"predecessor-version":[{"id":3532,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3531\/revisions\/3532"}],"wp:attachment":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=3531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=3531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=3531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}