
{"id":7201,"date":"2023-04-26T02:45:11","date_gmt":"2023-04-26T07:45:11","guid":{"rendered":"https:\/\/www.control2000.com.mx\/blog\/?p=7201"},"modified":"2023-05-02T10:29:44","modified_gmt":"2023-05-02T15:29:44","slug":"ya-estan-llegando-las-devoluciones","status":"publish","type":"post","link":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/","title":{"rendered":"Ya est\u00e1n llegando las devoluciones"},"content":{"rendered":"\n<p>Pero las peque\u00f1as&#8230;Este testimonio es de un contribuyente que tiene a\u00f1os sin obtener su saldo a favor. Pero ahora que es poquito, resulta que el robot decidi\u00f3 levantarle el castigo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"786\" height=\"418\" src=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg\" alt=\"\" class=\"wp-image-7202\" srcset=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg 786w, https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022-300x160.jpg 300w, https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022-768x408.jpg 768w\" sizes=\"(max-width: 786px) 100vw, 786px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"867\" height=\"617\" src=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Devolucion.jpg\" alt=\"\" class=\"wp-image-7212\" srcset=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Devolucion.jpg 867w, https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Devolucion-300x213.jpg 300w, https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Devolucion-768x547.jpg 768w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n\n\n<p>Recuerda que si no tuviste tu devoluci\u00f3n autom\u00e1tica, puedes recurrir a otras opciones para obtener tu <a href=\"https:\/\/www.control2000.com.mx\/blog\/no-todos-se-sacan-la-loteria\/\" target=\"_blank\" rel=\"noreferrer noopener\">saldo a favor. <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pero las peque\u00f1as&#8230;Este testimonio es de un contribuyente que tiene a\u00f1os sin obtener su saldo a favor. Pero ahora que es poquito, resulta que el robot decidi\u00f3 levantarle el castigo.<\/p>\n<p>Recuerda que si no tuviste tu devoluci\u00f3n autom\u00e1tica, [&#8230;]<a class=\"read-more read-more-c2k\" href=\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[271,145],"tags":[281,125,54],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ya est\u00e1n llegando las devoluciones - Blog 2000<\/title>\n<meta name=\"description\" content=\"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya est\u00e1n llegando las devoluciones - Blog 2000\" \/>\n<meta property=\"og:description\" content=\"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog 2000\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T07:45:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-02T15:29:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pen\u00e9lope Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/\",\"name\":\"Blog 2000\",\"description\":\"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#primaryimage\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg\",\"contentUrl\":\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg\",\"width\":786,\"height\":418},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#webpage\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/\",\"name\":\"Ya est\u00e1n llegando las devoluciones - Blog 2000\",\"isPartOf\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#primaryimage\"},\"datePublished\":\"2023-04-26T07:45:11+00:00\",\"dateModified\":\"2023-05-02T15:29:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\"},\"description\":\"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.control2000.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ya est\u00e1n llegando las devoluciones\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\",\"name\":\"Pen\u00e9lope Castro\",\"sameAs\":[\"http:\/\/www.control2000.com.mx\"],\"url\":\"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ya est\u00e1n llegando las devoluciones - Blog 2000","description":"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/","og_locale":"es_ES","og_type":"article","og_title":"Ya est\u00e1n llegando las devoluciones - Blog 2000","og_description":"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.","og_url":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/","og_site_name":"Blog 2000","article_published_time":"2023-04-26T07:45:11+00:00","article_modified_time":"2023-05-02T15:29:44+00:00","og_image":[{"url":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pen\u00e9lope Castro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.control2000.com.mx\/blog\/#website","url":"https:\/\/www.control2000.com.mx\/blog\/","name":"Blog 2000","description":"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#primaryimage","url":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg","contentUrl":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/IMG-20230424-WA0022.jpg","width":786,"height":418},{"@type":"WebPage","@id":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#webpage","url":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/","name":"Ya est\u00e1n llegando las devoluciones - Blog 2000","isPartOf":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#primaryimage"},"datePublished":"2023-04-26T07:45:11+00:00","dateModified":"2023-05-02T15:29:44+00:00","author":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791"},"description":"Una pregunta obligada en esta \u00e9poca: \u00bfya te hicieron la devoluci\u00f3n tu saldo a favor de ISR? Comp\u00e1rtenos tu experiencia.","breadcrumb":{"@id":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.control2000.com.mx\/blog\/ya-estan-llegando-las-devoluciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.control2000.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Ya est\u00e1n llegando las devoluciones"}]},{"@type":"Person","@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791","name":"Pen\u00e9lope Castro","sameAs":["http:\/\/www.control2000.com.mx"],"url":"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/"}]}},"fimg_url":false,"_links":{"self":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/7201"}],"collection":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=7201"}],"version-history":[{"count":5,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/7201\/revisions"}],"predecessor-version":[{"id":7242,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/7201\/revisions\/7242"}],"wp:attachment":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=7201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=7201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=7201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}