
{"id":8042,"date":"2024-04-04T04:10:32","date_gmt":"2024-04-04T09:10:32","guid":{"rendered":"https:\/\/www.control2000.com.mx\/blog\/?p=8042"},"modified":"2024-04-09T12:02:48","modified_gmt":"2024-04-09T17:02:48","slug":"en-resico-las-deducciones-funcionan-de-formas-insospechadas","status":"publish","type":"post","link":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/","title":{"rendered":"En RESICO las deducciones funcionan de formas insospechadas"},"content":{"rendered":"\n<p>Cuando damos por sentadas las cosas sin leer con detenimiento lo que nos est\u00e1n vendiendo, pasan cosas como esta.<\/p>\n\n\n\n<p>Y es que las Sociedades Civiles no necesitaban cambiarse a RESICO para utilizar un esquema de pago de impuestos en flujo de efectivo. Ya lo ten\u00edan, pero nadie le aviso eso al robot y el cambio para la mayor\u00eda fue autom\u00e1tico.<\/p>\n\n\n\n<p>Las que se dieron cuenta del riesgo corrigieron a tiempo. Sin embargo, otras siguen ah\u00ed, con la restricci\u00f3n de no poder dar un tratamiento adecuado los anticipos que pagan a sus socios bajo el esquema de asimilados, porque est\u00e1n concebidas para distribuir la utilidad de esta forma, ya que esta figura se concibe para dar un servicio profesional pero a trav\u00e9s de una persona moral.<\/p>\n\n\n\n<p>Lo que ocurri\u00f3 es que al analizar los conceptos deducibles en el R\u00e9gimen Simplificado de Confianza, no se incluyeron estos anticipos a los socios y el resto de la historia es la jurisprudencia que adjunto abajo.<\/p>\n\n\n\n<div class=\"is-layout-constrained wp-block-group\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Tesis-RESICO-deduccion-anticipos-a-socios.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Tesis-RESICO-deduccion-anticipos-a-socios.\"><\/object><a id=\"wp-block-file--media-939d7d3d-fe5c-47d2-b343-6be10e36de95\" href=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Tesis-RESICO-deduccion-anticipos-a-socios.pdf\">Tesis-RESICO-deduccion-anticipos-a-socios<\/a><a href=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Tesis-RESICO-deduccion-anticipos-a-socios.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-939d7d3d-fe5c-47d2-b343-6be10e36de95\">Descarga<\/a><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuando damos por sentadas las cosas sin leer con detenimiento lo que nos est\u00e1n vendiendo, pasan cosas como esta.<\/p>\n<p>Y es que las Sociedades Civiles no necesitaban cambiarse a RESICO para utilizar un esquema de pago de impuestos en flujo de efectivo. [&#8230;]<a class=\"read-more read-more-c2k\" href=\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":8074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1050,85],"tags":[1150,909,116,1058,1151],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En RESICO las deducciones funcionan de formas insospechadas - Blog 2000<\/title>\n<meta name=\"description\" content=\"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En RESICO las deducciones funcionan de formas insospechadas - Blog 2000\" \/>\n<meta property=\"og:description\" content=\"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog 2000\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T09:10:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T17:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pen\u00e9lope Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/\",\"name\":\"Blog 2000\",\"description\":\"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#primaryimage\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png\",\"contentUrl\":\"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png\",\"width\":1200,\"height\":630,\"caption\":\"\u00bfQu\u00e9 est\u00e1s pasando con las Sociedades Civiles que se cambiaron a RESICO?\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#webpage\",\"url\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/\",\"name\":\"En RESICO las deducciones funcionan de formas insospechadas - Blog 2000\",\"isPartOf\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#primaryimage\"},\"datePublished\":\"2024-04-04T09:10:32+00:00\",\"dateModified\":\"2024-04-09T17:02:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\"},\"description\":\"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.control2000.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En RESICO las deducciones funcionan de formas insospechadas\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791\",\"name\":\"Pen\u00e9lope Castro\",\"sameAs\":[\"http:\/\/www.control2000.com.mx\"],\"url\":\"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En RESICO las deducciones funcionan de formas insospechadas - Blog 2000","description":"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/","og_locale":"es_ES","og_type":"article","og_title":"En RESICO las deducciones funcionan de formas insospechadas - Blog 2000","og_description":"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.","og_url":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/","og_site_name":"Blog 2000","article_published_time":"2024-04-04T09:10:32+00:00","article_modified_time":"2024-04-09T17:02:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pen\u00e9lope Castro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.control2000.com.mx\/blog\/#website","url":"https:\/\/www.control2000.com.mx\/blog\/","name":"Blog 2000","description":"Consejos, tips y noticias, especialmente creados para ti. Somos desarrolladores de soluciones de software administrativo, contable y fiscal para las peque\u00f1as, medianas y grandes empresas en proceso de crecimiento y estabilidad.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.control2000.com.mx\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#primaryimage","url":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png","contentUrl":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png","width":1200,"height":630,"caption":"\u00bfQu\u00e9 est\u00e1s pasando con las Sociedades Civiles que se cambiaron a RESICO?"},{"@type":"WebPage","@id":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#webpage","url":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/","name":"En RESICO las deducciones funcionan de formas insospechadas - Blog 2000","isPartOf":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#primaryimage"},"datePublished":"2024-04-04T09:10:32+00:00","dateModified":"2024-04-09T17:02:48+00:00","author":{"@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791"},"description":"Unas de las razones por las que RESICO no resulta ser un r\u00e9gimen tan atractivo para las personas morales se debe a las deducciones.","breadcrumb":{"@id":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.control2000.com.mx\/blog\/en-resico-las-deducciones-funcionan-de-formas-insospechadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.control2000.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"En RESICO las deducciones funcionan de formas insospechadas"}]},{"@type":"Person","@id":"https:\/\/www.control2000.com.mx\/blog\/#\/schema\/person\/48d0cea52d4d24e32f61ed8ed768b791","name":"Pen\u00e9lope Castro","sameAs":["http:\/\/www.control2000.com.mx"],"url":"https:\/\/www.control2000.com.mx\/blog\/author\/penelope-castro\/"}]}},"fimg_url":"https:\/\/www.control2000.com.mx\/blog\/wp-content\/uploads\/Sociedad_RESICO-630-202402.png","_links":{"self":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/8042"}],"collection":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=8042"}],"version-history":[{"count":4,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/8042\/revisions"}],"predecessor-version":[{"id":8073,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/posts\/8042\/revisions\/8073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/media\/8074"}],"wp:attachment":[{"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=8042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=8042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.control2000.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=8042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}